{"id":29693,"date":"2026-05-06T17:43:29","date_gmt":"2026-05-06T10:43:29","guid":{"rendered":"https:\/\/greener.bangkok.go.th\/?post_type=event&#038;p=29693"},"modified":"2026-05-06T17:43:32","modified_gmt":"2026-05-06T10:43:32","slug":"music-in-park-may","status":"publish","type":"event","link":"https:\/\/greener.bangkok.go.th\/en\/event\/music-in-park-may\/","title":{"rendered":"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23"},"content":{"rendered":"<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569<br>\u0e13 \u0e28\u0e32\u0e25\u0e32\u0e20\u0e34\u0e21\u0e23\u0e21\u0e22\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35<\/p>\n\n\n\n<p>\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569<br>\u0e13 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e2a\u0e16\u0e32\u0e19 \u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e34<br><\/p>\n\n\n\n<p>\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\u0e41\u0e25\u0e49\u0e27&#8230; \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e31\u0e01! \u0e15\u0e32\u0e23\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27<\/p>\n\n\n\n<p>\u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e15\u0e34\u0e14\u0e43\u0e08\u0e21\u0e39\u0e49\u0e14\u0e14\u0e35\u0e46 \u0e08\u0e32\u0e01\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e17\u0e21. \u0e08\u0e31\u0e14\u0e2b\u0e19\u0e31\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21! \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1b\u0e39\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e22\u0e41\u0e08\u0e4a\u0e2a \u0e04\u0e2d\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1f\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e27\u0e07\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e2a\u0e15\u0e23\u0e32 \u0e40\u0e23\u0e32\u0e08\u0e31\u0e14\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e44\u0e15\u0e25\u0e4c<\/p>\n\n\n\n<p>\u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e34\u0e19\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13:<\/p>\n\n\n\n<p>\u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e34: \u0e19\u0e31\u0e48\u0e07\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e46 \u0e0a\u0e21\u0e27\u0e34\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e38\u0e14\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19<\/p>\n\n\n\n<p>\u0e28\u0e32\u0e25\u0e32\u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35): \u0e14\u0e19\u0e15\u0e23\u0e35\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 100 \u0e1b\u0e35<\/p>\n\n\n\n<p>\u0e2a\u0e27\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e0a\u0e31\u0e22\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23: \u0e40\u0e2a\u0e1e\u0e14\u0e19\u0e15\u0e23\u0e35\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e1f\u0e35\u0e25\u0e14\u0e35\u0e21\u0e32\u0e01!<\/p>\n\n\n\n<p>\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e2a\u0e34\u0e23\u0e34: \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17<\/p>\n\n\n\n<p>\u0e2a\u0e27\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22: \u0e1f\u0e31\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e23\u0e31\u0e1a\u0e25\u0e21\u0e40\u0e22\u0e47\u0e19\u0e46 \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e38\u0e14\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19<\/p>\n\n\n\n<p>\u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c: \u0e08\u0e38\u0e14\u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e34\u0e19\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f \u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e2d\u0e27\u0e25\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07<\/p>\n\n\n\n<p>\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e19\u0e49\u0e33\u0e40\u0e22\u0e47\u0e19\u0e46 \u0e01\u0e31\u0e1a\u0e02\u0e19\u0e21\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a \u0e41\u0e25\u0e49\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e15\u0e34\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e19\u0e30 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e1f\u0e23\u0e35\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21! \u0e43\u0e04\u0e23\u0e43\u0e01\u0e25\u0e49\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19 \u0e41\u0e17\u0e47\u0e01\u0e0a\u0e27\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19\u0e40\u0e25\u0e22<\/p>\n\n\n\n<p><\/p>","protected":false},"featured_media":29694,"parent":0,"template":"","event-categorie":[46],"class_list":["post-29693","event","type-event","status-publish","has-post-thumbnail","hentry","event-categorie-free"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 - Greener Bangkok<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/greener.bangkok.go.th\/en\/event\/music-in-park-may\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 - Greener Bangkok\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569\u0e13 \u0e28\u0e32\u0e25\u0e32\u0e20\u0e34\u0e21\u0e23\u0e21\u0e22\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569\u0e13 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e2a\u0e16\u0e32\u0e19 \u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e34 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\u0e41\u0e25\u0e49\u0e27&#8230; \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e31\u0e01! \u0e15\u0e32\u0e23\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e15\u0e34\u0e14\u0e43\u0e08\u0e21\u0e39\u0e49\u0e14\u0e14\u0e35\u0e46 \u0e08\u0e32\u0e01\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e17\u0e21. \u0e08\u0e31\u0e14\u0e2b\u0e19\u0e31\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21! \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1b\u0e39\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e22\u0e41\u0e08\u0e4a\u0e2a \u0e04\u0e2d\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1f\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e27\u0e07\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e2a\u0e15\u0e23\u0e32 \u0e40\u0e23\u0e32\u0e08\u0e31\u0e14\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e34\u0e19\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13: \u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e34: \u0e19\u0e31\u0e48\u0e07\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e46 \u0e0a\u0e21\u0e27\u0e34\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e38\u0e14\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e28\u0e32\u0e25\u0e32\u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35): \u0e14\u0e19\u0e15\u0e23\u0e35\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 100 \u0e1b\u0e35 \u0e2a\u0e27\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e0a\u0e31\u0e22\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23: \u0e40\u0e2a\u0e1e\u0e14\u0e19\u0e15\u0e23\u0e35\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e1f\u0e35\u0e25\u0e14\u0e35\u0e21\u0e32\u0e01! \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e2a\u0e34\u0e23\u0e34: \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e2a\u0e27\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22: \u0e1f\u0e31\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e23\u0e31\u0e1a\u0e25\u0e21\u0e40\u0e22\u0e47\u0e19\u0e46 \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e38\u0e14\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19 \u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c: \u0e08\u0e38\u0e14\u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e34\u0e19\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f \u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e2d\u0e27\u0e25\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e19\u0e49\u0e33\u0e40\u0e22\u0e47\u0e19\u0e46 \u0e01\u0e31\u0e1a\u0e02\u0e19\u0e21\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a \u0e41\u0e25\u0e49\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e15\u0e34\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e19\u0e30 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e1f\u0e23\u0e35\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21! \u0e43\u0e04\u0e23\u0e43\u0e01\u0e25\u0e49\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19 \u0e41\u0e17\u0e47\u0e01\u0e0a\u0e27\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19\u0e40\u0e25\u0e22\" \/>\n<meta property=\"og:url\" content=\"https:\/\/greener.bangkok.go.th\/en\/event\/music-in-park-may\/\" \/>\n<meta property=\"og:site_name\" content=\"Greener Bangkok\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T10:43:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/greener.bangkok.go.th\/wp-content\/uploads\/2026\/05\/689218709_1405000734990290_6670606098601781260_n.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1414\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/\",\"url\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/\",\"name\":\"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 - Greener Bangkok\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/greener.bangkok.go.th\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/689218709_1405000734990290_6670606098601781260_n.webp\",\"datePublished\":\"2026-05-06T10:43:29+00:00\",\"dateModified\":\"2026-05-06T10:43:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/#primaryimage\",\"url\":\"https:\\\/\\\/greener.bangkok.go.th\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/689218709_1405000734990290_6670606098601781260_n.webp\",\"contentUrl\":\"https:\\\/\\\/greener.bangkok.go.th\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/689218709_1405000734990290_6670606098601781260_n.webp\",\"width\":1414,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/music-in-park-may\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/greener.bangkok.go.th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\",\"item\":\"https:\\\/\\\/greener.bangkok.go.th\\\/event\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/#website\",\"url\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/\",\"name\":\"Greener Bangkok\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/greenerbkk.wpengine.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 - Greener Bangkok","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/greener.bangkok.go.th\/en\/event\/music-in-park-may\/","og_locale":"en_US","og_type":"article","og_title":"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 - Greener Bangkok","og_description":"\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569\u0e13 \u0e28\u0e32\u0e25\u0e32\u0e20\u0e34\u0e21\u0e23\u0e21\u0e22\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2569\u0e13 \u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35\u0e2a\u0e16\u0e32\u0e19 \u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35 \u0e41\u0e25\u0e30 \u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e34 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21\u0e41\u0e25\u0e49\u0e27&#8230; \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e44\u0e21\u0e48\u0e21\u0e35\u0e1e\u0e31\u0e01! \u0e15\u0e32\u0e23\u0e32\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27 \u0e43\u0e04\u0e23\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e15\u0e34\u0e14\u0e43\u0e08\u0e21\u0e39\u0e49\u0e14\u0e14\u0e35\u0e46 \u0e08\u0e32\u0e01\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e41\u0e25\u0e49\u0e27 \u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e35\u0e49 \u0e01\u0e17\u0e21. \u0e08\u0e31\u0e14\u0e2b\u0e19\u0e31\u0e01\u0e01\u0e27\u0e48\u0e32\u0e40\u0e14\u0e34\u0e21! \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e1b\u0e39\u0e40\u0e2a\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e23\u0e31\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e17\u0e31\u0e48\u0e27\u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e32\u0e22\u0e41\u0e08\u0e4a\u0e2a \u0e04\u0e2d\u0e2d\u0e34\u0e19\u0e14\u0e35\u0e49 \u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1f\u0e19\u0e04\u0e25\u0e31\u0e1a\u0e27\u0e07\u0e2d\u0e2d\u0e23\u0e4c\u0e40\u0e04\u0e2a\u0e15\u0e23\u0e32 \u0e40\u0e23\u0e32\u0e08\u0e31\u0e14\u0e21\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e23\u0e1a\u0e17\u0e38\u0e01\u0e2a\u0e44\u0e15\u0e25\u0e4c \u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e34\u0e19\u0e1e\u0e34\u0e01\u0e31\u0e14\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e43\u0e01\u0e25\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e04\u0e38\u0e13: \u0e2a\u0e27\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e01\u0e34\u0e15\u0e34: \u0e19\u0e31\u0e48\u0e07\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e0a\u0e34\u0e25\u0e25\u0e4c\u0e46 \u0e0a\u0e21\u0e27\u0e34\u0e27\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e38\u0e14\u0e42\u0e21\u0e40\u0e14\u0e34\u0e23\u0e4c\u0e19 \u0e28\u0e32\u0e25\u0e32\u0e20\u0e34\u0e23\u0e21\u0e22\u0e4c\u0e20\u0e31\u0e01\u0e14\u0e35 (\u0e2a\u0e27\u0e19\u0e25\u0e38\u0e21\u0e1e\u0e34\u0e19\u0e35): \u0e14\u0e19\u0e15\u0e23\u0e35\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01\u0e17\u0e48\u0e32\u0e21\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e27\u0e31\u0e15\u0e34\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c 100 \u0e1b\u0e35 \u0e2a\u0e27\u0e19\u0e2a\u0e31\u0e19\u0e15\u0e34\u0e0a\u0e31\u0e22\u0e1b\u0e23\u0e32\u0e01\u0e32\u0e23: \u0e40\u0e2a\u0e1e\u0e14\u0e19\u0e15\u0e23\u0e35\u0e23\u0e34\u0e21\u0e41\u0e21\u0e48\u0e19\u0e49\u0e33\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e32 \u0e1f\u0e35\u0e25\u0e14\u0e35\u0e21\u0e32\u0e01! \u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e40\u0e1a\u0e0d\u0e08\u0e2a\u0e34\u0e23\u0e34: \u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e28\u0e34\u0e25\u0e1b\u0e30\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e08\u0e01\u0e25\u0e32\u0e07\u0e2a\u0e38\u0e02\u0e38\u0e21\u0e27\u0e34\u0e17 \u0e2a\u0e27\u0e19\u0e40\u0e2a\u0e23\u0e35\u0e44\u0e17\u0e22: \u0e1f\u0e31\u0e07\u0e14\u0e19\u0e15\u0e23\u0e35\u0e23\u0e31\u0e1a\u0e25\u0e21\u0e40\u0e22\u0e47\u0e19\u0e46 \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e38\u0e14\u0e23\u0e48\u0e21\u0e23\u0e37\u0e48\u0e19 \u0e2a\u0e27\u0e19\u0e18\u0e19\u0e1a\u0e38\u0e23\u0e35\u0e23\u0e21\u0e22\u0e4c: \u0e08\u0e38\u0e14\u0e40\u0e0a\u0e47\u0e01\u0e2d\u0e34\u0e19\u0e0a\u0e32\u0e27\u0e1d\u0e31\u0e48\u0e07\u0e18\u0e19\u0e2f \u0e17\u0e35\u0e48\u0e2d\u0e1a\u0e2d\u0e27\u0e25\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e1e\u0e25\u0e07 \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e19\u0e49\u0e33\u0e40\u0e22\u0e47\u0e19\u0e46 \u0e01\u0e31\u0e1a\u0e02\u0e19\u0e21\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a \u0e41\u0e25\u0e49\u0e27\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e40\u0e15\u0e34\u0e21\u0e1e\u0e25\u0e31\u0e07\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e19\u0e30 \u0e07\u0e32\u0e19\u0e19\u0e35\u0e49\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21\u0e1f\u0e23\u0e35\u0e17\u0e38\u0e01\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e14\u0e34\u0e21! \u0e43\u0e04\u0e23\u0e43\u0e01\u0e25\u0e49\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19 \u0e41\u0e17\u0e47\u0e01\u0e0a\u0e27\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19\u0e40\u0e25\u0e22","og_url":"https:\/\/greener.bangkok.go.th\/en\/event\/music-in-park-may\/","og_site_name":"Greener Bangkok","article_modified_time":"2026-05-06T10:43:32+00:00","og_image":[{"width":1414,"height":2000,"url":"https:\/\/greener.bangkok.go.th\/wp-content\/uploads\/2026\/05\/689218709_1405000734990290_6670606098601781260_n.webp","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/","url":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/","name":"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 - Greener Bangkok","isPartOf":{"@id":"https:\/\/greenerbkk.wpengine.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/#primaryimage"},"image":{"@id":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/#primaryimage"},"thumbnailUrl":"https:\/\/greener.bangkok.go.th\/wp-content\/uploads\/2026\/05\/689218709_1405000734990290_6670606098601781260_n.webp","datePublished":"2026-05-06T10:43:29+00:00","dateModified":"2026-05-06T10:43:32+00:00","breadcrumb":{"@id":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/#primaryimage","url":"https:\/\/greener.bangkok.go.th\/wp-content\/uploads\/2026\/05\/689218709_1405000734990290_6670606098601781260_n.webp","contentUrl":"https:\/\/greener.bangkok.go.th\/wp-content\/uploads\/2026\/05\/689218709_1405000734990290_6670606098601781260_n.webp","width":1414,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/greener.bangkok.go.th\/event\/music-in-park-may\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/greener.bangkok.go.th\/"},{"@type":"ListItem","position":2,"name":"\u0e1b\u0e0f\u0e34\u0e17\u0e34\u0e19\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21","item":"https:\/\/greener.bangkok.go.th\/event\/"},{"@type":"ListItem","position":3,"name":"\u0e14\u0e19\u0e15\u0e23\u0e35\u0e43\u0e19\u0e2a\u0e27\u0e19 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23"}]},{"@type":"WebSite","@id":"https:\/\/greenerbkk.wpengine.com\/#website","url":"https:\/\/greenerbkk.wpengine.com\/","name":"Greener Bangkok","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/greenerbkk.wpengine.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/greener.bangkok.go.th\/en\/wp-json\/wp\/v2\/event\/29693","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greener.bangkok.go.th\/en\/wp-json\/wp\/v2\/event"}],"about":[{"href":"https:\/\/greener.bangkok.go.th\/en\/wp-json\/wp\/v2\/types\/event"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/greener.bangkok.go.th\/en\/wp-json\/wp\/v2\/media\/29694"}],"wp:attachment":[{"href":"https:\/\/greener.bangkok.go.th\/en\/wp-json\/wp\/v2\/media?parent=29693"}],"wp:term":[{"taxonomy":"event-categorie","embeddable":true,"href":"https:\/\/greener.bangkok.go.th\/en\/wp-json\/wp\/v2\/event-categorie?post=29693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}